{"id":3705,"date":"2023-01-16T17:50:16","date_gmt":"2023-01-16T16:50:16","guid":{"rendered":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/?p=3705"},"modified":"2023-03-25T09:38:56","modified_gmt":"2023-03-25T08:38:56","slug":"quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee","status":"publish","type":"post","link":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html","title":{"rendered":"Qu&rsquo;est-ce que la chlorhexidine et comment est-elle utilis\u00e9e ?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #008000;color:#008000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #008000;color:#008000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html\/#Quest-ce_que_la_chlorhexidine\" >Qu&rsquo;est-ce que la chlorhexidine ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html\/#A_quoi_sert_la_chlorhexidine\" >A quoi sert la chlorhexidine ?<\/a><ul class='ez-toc-list-level-5' ><li class='ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html\/#Chlorhexidine_en_bain_de_bouche\" >Chlorhexidine en bain de bouche<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html\/#Gel_bioadhesif_a_la_chlorhexidine\" >Gel bioadh\u00e9sif \u00e0 la chlorhexidine<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html\/#Chlorhexidine_en_spray\" >Chlorhexidine en spray<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html\/#Comment_utiliser_la_chlorhexidine\" >Comment utiliser la chlorhexidine<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html\/#Effets_secondaires_de_la_chlorhexidine\" >Effets secondaires de la chlorhexidine<\/a><\/li><\/ul><\/nav><\/div>\n<h4><span class=\"ez-toc-section\" id=\"Quest-ce_que_la_chlorhexidine\"><\/span><span style=\"color: #008000;\"><strong>Qu&rsquo;est-ce que la chlorhexidine ?<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>C&rsquo;est un antiseptique topique pour la cicatrisation des plaies. Il est couramment utilis\u00e9 sous forme dilu\u00e9e pour traiter les l\u00e9sions de la muqueuse buccale.\u00a0 On citera le saignement des gencives, les aphtes ou les plaies de la langue.<\/p>\n<p><u>La chlorhexidine est utilis\u00e9e pour traiter les affections suivantes :<\/u><\/p>\n<p><strong>\u2022<\/strong>\u00a0De la peau (plaies),<br \/>\n<strong>\u2022<\/strong> De la bouche (<a href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/gingivite-causes-symptomes-et-traitements.html\"><strong>gingivite<\/strong><\/a>, parodontite, chirurgie buccale),<br \/>\n<strong>\u2022<\/strong> Et dans les processus chirurgicaux.<\/p>\n<p>Il est bact\u00e9riostatique, c&rsquo;est-\u00e0-dire qu&rsquo;il emp\u00eache la reproduction des bact\u00e9ries, qui sont responsables de l&rsquo;infection des plaies. Il agit donc comme un d\u00e9sinfectant.<\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"A_quoi_sert_la_chlorhexidine\"><\/span><span style=\"color: #008000;\"><strong>A quoi sert la chlorhexidine ?<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Il est couramment utilis\u00e9 en dentisterie, notamment pour les l\u00e9sions l\u00e9g\u00e8res de la muqueuse buccale. Il est \u00e9galement utilis\u00e9 dans le<a href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/9-choses-a-savoir-sur-le-traitement-de-la-parodontite.html\"><strong> traitement des gingivites et des parodontites<\/strong><\/a> et dans la pr\u00e9vention des infections lors d&rsquo;interventions chirurgicales ou buccales.<\/p>\n<p>Il est utilis\u00e9 dilu\u00e9 \u00e0 des concentrations de 0,2%, 0,12% et 0,10% ainsi que sous forme de gels, de sprays et de dentifrices.<\/p>\n<p>&nbsp;<\/p>\n<h5><span class=\"ez-toc-section\" id=\"Chlorhexidine_en_bain_de_bouche\"><\/span><strong>Chlorhexidine en bain de bouche<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h5>\n<p>La chlorhexidine en tant que <a href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quel-choix-pour-un-meilleur-bain-de-bouche.html\"><strong>bain de bouche<\/strong><\/a> est le seul bain de bouche d\u00e9sinfectant dont la capacit\u00e9 \u00e0 tuer les bact\u00e9ries est scientifiquement prouv\u00e9e, selon les experts du domaine.<\/p>\n<p><u>Il est recommand\u00e9 de l&rsquo;utiliser sur prescription d&rsquo;un dentiste, mais il est normalement utilis\u00e9 pour :<\/u><\/p>\n<p><strong>\u2022<\/strong> S&rsquo;attaquer aux bact\u00e9ries d&rsquo;une infection des gencives (parodontite), qui provoque leur inflammation (gingivite) et qui, si elle n&rsquo;est pas soign\u00e9e \u00e0 temps, peut endommager les os des dents,<br \/>\n<strong>\u2022<\/strong> Apr\u00e8s l&rsquo;op\u00e9ration, pour \u00e9viter toute infection, \u00e9vitez de nettoyer la zone autour de la plaie avec une brosse.<\/p>\n<p>Il est parfois recommand\u00e9 de traiter les plaies, mais si celles-ci sont dues \u00e0 un probl\u00e8me d&rsquo;estomac ou \u00e0 de faibles d\u00e9fenses, cela ne r\u00e9soudra rien.<\/p>\n<p>&nbsp;<\/p>\n<h5><span class=\"ez-toc-section\" id=\"Gel_bioadhesif_a_la_chlorhexidine\"><\/span><strong>Gel bioadh\u00e9sif \u00e0 la chlorhexidine<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h5>\n<p>Le gel bioadh\u00e9sif \u00e0 la chlorhexidine forme un film protecteur sur la zone appliqu\u00e9e et aide \u00e0 maintenir la zone mieux prot\u00e9g\u00e9e plus longtemps.<\/p>\n<p>Selon les experts, il doit \u00eatre appliqu\u00e9 2 \u00e0 3 fois par jour, apr\u00e8s une bonne hygi\u00e8ne buccale. Mais pas pour une longue dur\u00e9e.<\/p>\n<p>Il est recommand\u00e9 pour traiter les plaies et les inflammations caus\u00e9es par les implants, l&rsquo;orthodontie ou la chirurgie parodontale. Il est \u00e9galement efficace pour traiter les petites l\u00e9sions telles que les <a href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/les-aphtes.html\"><strong>aphtes<\/strong><\/a>, ainsi que les gingivites et les parodontites.<\/p>\n<p>&nbsp;<\/p>\n<h5><span class=\"ez-toc-section\" id=\"Chlorhexidine_en_spray\"><\/span><strong>Chlorhexidine en spray<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h5>\n<p>Le spray a la m\u00eame fonction que le bain de bouche : il sert d&rsquo;adjuvant dans le traitement parodontal, pour <a href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/comment-soigner-la-gingivite.html\"><strong>soigner la gingivit<\/strong><\/a>e ou d&rsquo;autres cas.<\/p>\n<p>Pour les l\u00e9sions localis\u00e9es, par exemple apr\u00e8s une extraction dentaire, la chlorhexidine est souvent utilis\u00e9e sous forme de spray pour \u00e9viter que la zone affect\u00e9e ne s&rsquo;infecte.<\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Comment_utiliser_la_chlorhexidine\"><\/span><span style=\"color: #008000;\"><strong>Comment utiliser la chlorhexidine<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Elle ne doit pas \u00eatre utilis\u00e9e pendant de tr\u00e8s longues p\u00e9riodes car elle provoque une pigmentation des tissus, ce qui entra\u00eene un jaunissement des dents. Il peut \u00e9galement favoriser les candidoses et, en cas d&rsquo;utilisation prolong\u00e9e, il peut provoquer des alt\u00e9rations du sens du go\u00fbt.<\/p>\n<p>Les dentistes recommandent des bains de bouche \u00e0 la chlorhexidine pour une dur\u00e9e moyenne de 2 semaines et exceptionnellement pour un mois.<\/p>\n<p>Il doit \u00eatre utilis\u00e9 deux fois par jour, une fois le soir.<\/p>\n<p>Dans tous les cas, suivez les directives de votre dentiste pour son utilisation. D&rsquo;autres conseils sont : ne pas manger pendant une demi-heure apr\u00e8s le rin\u00e7age et ne pas m\u00e9langer avec de l&rsquo;eau ou avaler.<\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Effets_secondaires_de_la_chlorhexidine\"><\/span><span style=\"color: #008000;\"><strong>Effets secondaires de la chlorhexidine<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Elle a des effets secondaires et ne doit donc pas \u00eatre utilis\u00e9e sans l&rsquo;avis d&rsquo;un expert. Voici quelques-uns des effets secondaires de la chlorhexidine :<\/p>\n<p><strong>\u2022<\/strong> Il tache et assombrit les dents et la langue s&rsquo;il est utilis\u00e9 pendant une p\u00e9riode prolong\u00e9e,<br \/>\n<strong>\u2022<\/strong> Il alt\u00e8re le sens du go\u00fbt et le rend \u00e9trange,<br \/>\n<strong>\u2022<\/strong> Il ne discrimine pas les bact\u00e9ries et \u00e9limine celles qui remplissent une fonction n\u00e9cessaire dans notre bouche. Une utilisation prolong\u00e9e peut donc endommager le microsyst\u00e8me oral.<\/p>\n<p>Ces effets sont r\u00e9versibles si l&rsquo;on cesse d&rsquo;utiliser la chlorhexidine. Le go\u00fbt est r\u00e9tabli peu apr\u00e8s l&rsquo;arr\u00eat du produit. La couleur des dents peut \u00eatre restaur\u00e9e avec l&rsquo;aide d&rsquo;un dentiste.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu&rsquo;est-ce que la chlorhexidine ? C&rsquo;est un antiseptique topique pour la cicatrisation des plaies. Il est couramment utilis\u00e9 sous forme<\/p>\n","protected":false},"author":1,"featured_media":3711,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_lmt_disableupdate":"no","_lmt_disable":"no","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4],"tags":[132,523],"class_list":["post-3705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vos-questions","tag-bain-de-bouche","tag-chlorhexidine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu&#039;est-ce que la chlorhexidine et comment est-elle utilis\u00e9e ? -<\/title>\n<meta name=\"description\" content=\"La chlorhexidine est un antiseptique topique pour la cicatrisation des plaies. Dilu\u00e9e, elle est utilis\u00e9 pour traiter les l\u00e9sions buccales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu&#039;est-ce que la chlorhexidine et comment est-elle utilis\u00e9e ? -\" \/>\n<meta property=\"og:description\" content=\"La chlorhexidine est un antiseptique topique pour la cicatrisation des plaies. Dilu\u00e9e, elle est utilis\u00e9 pour traiter les l\u00e9sions buccales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html\" \/>\n<meta property=\"og:site_name\" content=\"Ma sant\u00e9 bucco-dentaire\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ma-sant-bucco-dentaire-106538034609903\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Ma-sant-bucco-dentaire-106538034609903\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-16T16:50:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-25T08:38:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2022\/01\/chlorhexidine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"356\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/vos-questions\\\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/vos-questions\\\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/#\\\/schema\\\/person\\\/b60c4ef676e6f6aecf24be3a2b1d7f42\"},\"headline\":\"Qu&rsquo;est-ce que la chlorhexidine et comment est-elle utilis\u00e9e ?\",\"datePublished\":\"2023-01-16T16:50:16+00:00\",\"dateModified\":\"2023-03-25T08:38:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/vos-questions\\\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html\"},\"wordCount\":717,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/#\\\/schema\\\/person\\\/b60c4ef676e6f6aecf24be3a2b1d7f42\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/vos-questions\\\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/chlorhexidine.jpg\",\"keywords\":[\"bain de bouche\",\"Chlorhexidine\"],\"articleSection\":[\"V0S QUESTIONS\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/vos-questions\\\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html\",\"url\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/vos-questions\\\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html\",\"name\":\"Qu'est-ce que la chlorhexidine et comment est-elle utilis\u00e9e ? -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/vos-questions\\\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/vos-questions\\\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/chlorhexidine.jpg\",\"datePublished\":\"2023-01-16T16:50:16+00:00\",\"dateModified\":\"2023-03-25T08:38:56+00:00\",\"description\":\"La chlorhexidine est un antiseptique topique pour la cicatrisation des plaies. Dilu\u00e9e, elle est utilis\u00e9 pour traiter les l\u00e9sions buccales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/vos-questions\\\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/vos-questions\\\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/vos-questions\\\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/chlorhexidine.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/chlorhexidine.jpg\",\"width\":640,\"height\":356,\"caption\":\"Qu'est-ce que la chlorhexidine et comment est-elle utilis\u00e9e ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/vos-questions\\\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu&rsquo;est-ce que la chlorhexidine et comment est-elle utilis\u00e9e ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/#website\",\"url\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/\",\"name\":\"Ma sant\u00e9 bucco-dentaire\",\"description\":\"Informations et conseils dentaires pour patient\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/#\\\/schema\\\/person\\\/b60c4ef676e6f6aecf24be3a2b1d7f42\"},\"alternateName\":\"Sant\u00e9 bucco-dentaire\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/#\\\/schema\\\/person\\\/b60c4ef676e6f6aecf24be3a2b1d7f42\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Ma-sante-dentaire2.jpg\",\"url\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Ma-sante-dentaire2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Ma-sante-dentaire2.jpg\",\"width\":290,\"height\":75,\"caption\":\"Admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Ma-sante-dentaire2.jpg\"},\"sameAs\":[\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\",\"https:\\\/\\\/www.facebook.com\\\/Ma-sant-bucco-dentaire-106538034609903\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu'est-ce que la chlorhexidine et comment est-elle utilis\u00e9e ? -","description":"La chlorhexidine est un antiseptique topique pour la cicatrisation des plaies. Dilu\u00e9e, elle est utilis\u00e9 pour traiter les l\u00e9sions buccales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html","og_locale":"fr_FR","og_type":"article","og_title":"Qu'est-ce que la chlorhexidine et comment est-elle utilis\u00e9e ? -","og_description":"La chlorhexidine est un antiseptique topique pour la cicatrisation des plaies. Dilu\u00e9e, elle est utilis\u00e9 pour traiter les l\u00e9sions buccales.","og_url":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html","og_site_name":"Ma sant\u00e9 bucco-dentaire","article_publisher":"https:\/\/www.facebook.com\/Ma-sant-bucco-dentaire-106538034609903","article_author":"https:\/\/www.facebook.com\/Ma-sant-bucco-dentaire-106538034609903","article_published_time":"2023-01-16T16:50:16+00:00","article_modified_time":"2023-03-25T08:38:56+00:00","og_image":[{"width":640,"height":356,"url":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2022\/01\/chlorhexidine.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html#article","isPartOf":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html"},"author":{"name":"Admin","@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/#\/schema\/person\/b60c4ef676e6f6aecf24be3a2b1d7f42"},"headline":"Qu&rsquo;est-ce que la chlorhexidine et comment est-elle utilis\u00e9e ?","datePublished":"2023-01-16T16:50:16+00:00","dateModified":"2023-03-25T08:38:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html"},"wordCount":717,"publisher":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/#\/schema\/person\/b60c4ef676e6f6aecf24be3a2b1d7f42"},"image":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2022\/01\/chlorhexidine.jpg","keywords":["bain de bouche","Chlorhexidine"],"articleSection":["V0S QUESTIONS"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html","url":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html","name":"Qu'est-ce que la chlorhexidine et comment est-elle utilis\u00e9e ? -","isPartOf":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html#primaryimage"},"image":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2022\/01\/chlorhexidine.jpg","datePublished":"2023-01-16T16:50:16+00:00","dateModified":"2023-03-25T08:38:56+00:00","description":"La chlorhexidine est un antiseptique topique pour la cicatrisation des plaies. Dilu\u00e9e, elle est utilis\u00e9 pour traiter les l\u00e9sions buccales.","breadcrumb":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html#primaryimage","url":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2022\/01\/chlorhexidine.jpg","contentUrl":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2022\/01\/chlorhexidine.jpg","width":640,"height":356,"caption":"Qu'est-ce que la chlorhexidine et comment est-elle utilis\u00e9e ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/quest-ce-que-la-chlorhexidine-et-comment-est-elle-utilisee.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lecourrierdudentiste.com\/lepatient"},{"@type":"ListItem","position":2,"name":"Qu&rsquo;est-ce que la chlorhexidine et comment est-elle utilis\u00e9e ?"}]},{"@type":"WebSite","@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/#website","url":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/","name":"Ma sant\u00e9 bucco-dentaire","description":"Informations et conseils dentaires pour patient","publisher":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/#\/schema\/person\/b60c4ef676e6f6aecf24be3a2b1d7f42"},"alternateName":"Sant\u00e9 bucco-dentaire","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/#\/schema\/person\/b60c4ef676e6f6aecf24be3a2b1d7f42","name":"Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2020\/11\/Ma-sante-dentaire2.jpg","url":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2020\/11\/Ma-sante-dentaire2.jpg","contentUrl":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2020\/11\/Ma-sante-dentaire2.jpg","width":290,"height":75,"caption":"Admin"},"logo":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2020\/11\/Ma-sante-dentaire2.jpg"},"sameAs":["https:\/\/www.lecourrierdudentiste.com\/lepatient","https:\/\/www.facebook.com\/Ma-sant-bucco-dentaire-106538034609903"]}]}},"modified_by":"Admin","jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2022\/01\/chlorhexidine.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/posts\/3705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/comments?post=3705"}],"version-history":[{"count":10,"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/posts\/3705\/revisions"}],"predecessor-version":[{"id":4022,"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/posts\/3705\/revisions\/4022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/media\/3711"}],"wp:attachment":[{"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/media?parent=3705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/categories?post=3705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/tags?post=3705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}