{"id":1630,"date":"2021-07-05T20:13:00","date_gmt":"2021-07-05T18:13:00","guid":{"rendered":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/?p=1630"},"modified":"2021-07-06T06:05:45","modified_gmt":"2021-07-06T04:05:45","slug":"la-fluorose-dentaire","status":"publish","type":"post","link":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html","title":{"rendered":"La fluorose dentaire"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #008000;color:#008000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #008000;color:#008000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html\/#Quest-ce_que_la_fluorose_dentaire\" >Qu&rsquo;est-ce que la fluorose dentaire ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html\/#Quelles_sont_les_causes_de_la_fluorose_dentaire\" >Quelles sont les causes de la fluorose dentaire ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html\/#De_quelle_quantite_de_fluorure_mon_enfant_a-t-il_besoin_pour_proteger_ses_dents\" >De quelle quantit\u00e9 de fluorure mon enfant a-t-il besoin pour prot\u00e9ger ses dents ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html\/#Comment_puis-je_savoir_si_mon_enfant_est_atteint_de_fluorose_dentaire\" >Comment puis-je savoir si mon enfant est atteint de fluorose dentaire ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html\/#Comment_puis-je_proteger_les_dents_de_mon_enfant_sans_provoquer_de_fluorose\" >Comment puis-je prot\u00e9ger les dents de mon enfant sans provoquer de fluorose ?<\/a><ul class='ez-toc-list-level-5' ><li class='ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html\/#1-_Assurez-vous_que_les_enfants_utilisent_les_produits_dentaires_recommandes\" >1- Assurez-vous que les enfants utilisent les produits dentaires recommand\u00e9s.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html\/#2-_Assurez-vous_que_votre_enfant_boit_de_leau_fluoree\" >2- Assurez-vous que votre enfant boit de l&rsquo;eau fluor\u00e9e<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html\/#3-_Commencez_des_visites_regulieres_chez_le_dentiste_avant_le_premier_anniversaire_de_votre_enfant\" >3- Commencez des visites r\u00e9guli\u00e8res chez le dentiste avant le premier anniversaire de votre enfant.<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<p>Le fluorure est un min\u00e9ral important pour tous les enfants. Nos bouches contiennent des bact\u00e9ries qui, combin\u00e9es aux sucres des aliments que nous mangeons et des boissons que nous buvons, produisent un acide qui nuit \u00e0 nos dents. Le fluorure prot\u00e8ge nos dents. Mais une trop grande quantit\u00e9 de fluorure peut provoquer ce qu&rsquo;on appelle la fluorose dentaire.<\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Quest-ce_que_la_fluorose_dentaire\"><\/span><span style=\"color: #008000;\"><strong>Qu&rsquo;est-ce que la fluorose dentaire ?<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>La fluorose dentaire est une l\u00e9g\u00e8re modification de l&rsquo;aspect des dents, g\u00e9n\u00e9ralement sous la forme de tr\u00e8s l\u00e9g\u00e8res marques blanches. Elle n&rsquo;affecte normalement pas la fonction des dents et ne provoque pas de douleur.<\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Quelles_sont_les_causes_de_la_fluorose_dentaire\"><\/span><span style=\"color: #008000;\"><strong>Quelles sont les causes de la fluorose dentaire ?<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>La plupart des fluoroses sont le r\u00e9sultat d&rsquo;une consommation excessive de fluor avant l&rsquo;\u00e2ge de 8 ans, alors que les dents permanentes sont encore en formation. Veillez \u00e0 ce que les enfants apprennent \u00e0 recracher le dentifrice et non \u00e0 l&rsquo;avaler.<\/p>\n<p>Les enfants peuvent contracter la fluorose \u00e0 partir d\u2019eau courante riche en fluor notamment dans les r\u00e9gions d\u2019exploitation des phosphates o\u00f9 la teneur en fluorure dans l\u2019eau est tr\u00e8s \u00e9lev\u00e9e.<\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"De_quelle_quantite_de_fluorure_mon_enfant_a-t-il_besoin_pour_proteger_ses_dents\"><\/span><span style=\"color: #008000;\"><strong>De quelle quantit\u00e9 de fluorure mon enfant a-t-il besoin pour prot\u00e9ger ses dents ?<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Les enfants qui ont un r\u00e9gime alimentaire normal, boivent de l&rsquo;eau fluor\u00e9e et utilisent correctement des produits dentaires fluor\u00e9s re\u00e7oivent le fluorure dont ils ont besoin pour avoir des dents saines.<\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Comment_puis-je_savoir_si_mon_enfant_est_atteint_de_fluorose_dentaire\"><\/span><span style=\"color: #008000;\"><strong>Comment puis-je savoir si mon enfant est atteint de fluorose dentaire ?<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u00c9tant donn\u00e9 que les changements d&rsquo;apparence des dents peuvent avoir de nombreuses causes, vous pouvez consulter un professionnel des soins dentaires pour faire v\u00e9rifier si les dents sont fluor\u00e9es ou si elles pr\u00e9sentent d&rsquo;autres probl\u00e8mes.<\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Comment_puis-je_proteger_les_dents_de_mon_enfant_sans_provoquer_de_fluorose\"><\/span><span style=\"color: #008000;\"><strong>Comment puis-je prot\u00e9ger les dents de mon enfant sans provoquer de fluorose ?<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Voici trois choses que vous pouvez faire :<\/p>\n<h5><span class=\"ez-toc-section\" id=\"1-_Assurez-vous_que_les_enfants_utilisent_les_produits_dentaires_recommandes\"><\/span><strong>1- Assurez-vous que les enfants utilisent les produits dentaires recommand\u00e9s.<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h5>\n<p>&#8211; Les enfants doivent utiliser du dentifrice fluor\u00e9 deux fois par jour (une \u00a0\u00bb tache \u00a0\u00bb pour les enfants de moins de 3 ans et une quantit\u00e9 de la taille d&rsquo;un petit pois pour les enfants de plus de 3 ans).<\/p>\n<p>&#8211; Les enfants de moins de 6 ans ne doivent pas utiliser de bain de bouche.<\/p>\n<p>&#8211; Veillez \u00e0 ce que les enfants sachent qu&rsquo;ils doivent cracher, et non avaler, l&rsquo;exc\u00e9dent de dentifrice.<\/p>\n<p>&nbsp;<\/p>\n<h5><span class=\"ez-toc-section\" id=\"2-_Assurez-vous_que_votre_enfant_boit_de_leau_fluoree\"><\/span><strong>2- Assurez-vous que votre enfant boit de l&rsquo;eau fluor\u00e9e<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h5>\n<p>&#8211; Pour v\u00e9rifier si votre eau locale est fluor\u00e9e, consultez les sites Web de votre fournisseur d\u2019eau courante.<\/p>\n<p>&#8211; Si vos enfants ne boivent pas d&rsquo;<a href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/vos-questions\/le-fluor-et-la-sante-des-dents-bon-ou-mauvais.html\">eau fluor\u00e9e<\/a>, demandez \u00e0 votre m\u00e9decin s&rsquo;ils ont besoin d&rsquo;un suppl\u00e9ment de fluor prescrit.<\/p>\n<p>&nbsp;<\/p>\n<h5><span class=\"ez-toc-section\" id=\"3-_Commencez_des_visites_regulieres_chez_le_dentiste_avant_le_premier_anniversaire_de_votre_enfant\"><\/span><strong>3- Commencez des visites r\u00e9guli\u00e8res chez le dentiste avant le premier anniversaire de votre enfant.<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h5>\n<p>&#8211; Si vous n&rsquo;avez pas encore de dentiste, le m\u00e9decin de votre enfant peut vous en recommander un. Le m\u00e9decin peut \u00e9galement examiner les dents de votre enfant, vous expliquer comment prendre soin de sa sant\u00e9 bucco-dentaire et s&rsquo;assurer qu&rsquo;il re\u00e7oit suffisamment de fluor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le fluorure est un min\u00e9ral important pour tous les enfants. Nos bouches contiennent des bact\u00e9ries qui, combin\u00e9es aux sucres des<\/p>\n","protected":false},"author":1,"featured_media":1631,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_lmt_disableupdate":"","_lmt_disable":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[213,211,212],"class_list":["post-1630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-fluor","tag-fluorose-dentaire","tag-fluorure"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La fluorose dentaire - Fluorure - Ma sant\u00e9 bucco-dentaire<\/title>\n<meta name=\"description\" content=\"La fluorose dentaire est une l\u00e9g\u00e8re modification de l&#039;aspect des dents, g\u00e9n\u00e9ralement sous la forme de tr\u00e8s l\u00e9g\u00e8res marques blanches ou jaun\u00e2tres.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La fluorose dentaire - Fluorure - Ma sant\u00e9 bucco-dentaire\" \/>\n<meta property=\"og:description\" content=\"La fluorose dentaire est une l\u00e9g\u00e8re modification de l&#039;aspect des dents, g\u00e9n\u00e9ralement sous la forme de tr\u00e8s l\u00e9g\u00e8res marques blanches ou jaun\u00e2tres.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html\" \/>\n<meta property=\"og:site_name\" content=\"Ma sant\u00e9 bucco-dentaire\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ma-sant-bucco-dentaire-106538034609903\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Ma-sant-bucco-dentaire-106538034609903\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-05T18:13:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-06T04:05:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2021\/07\/fluorose.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"356\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/blog\\\/la-fluorose-dentaire.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/blog\\\/la-fluorose-dentaire.html\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/#\\\/schema\\\/person\\\/b60c4ef676e6f6aecf24be3a2b1d7f42\"},\"headline\":\"La fluorose dentaire\",\"datePublished\":\"2021-07-05T18:13:00+00:00\",\"dateModified\":\"2021-07-06T04:05:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/blog\\\/la-fluorose-dentaire.html\"},\"wordCount\":516,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/#\\\/schema\\\/person\\\/b60c4ef676e6f6aecf24be3a2b1d7f42\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/blog\\\/la-fluorose-dentaire.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/fluorose.jpg\",\"keywords\":[\"Fluor\",\"Fluorose dentaire\",\"Fluorure\"],\"articleSection\":[\"BLOG\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/blog\\\/la-fluorose-dentaire.html\",\"url\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/blog\\\/la-fluorose-dentaire.html\",\"name\":\"La fluorose dentaire - Fluorure - Ma sant\u00e9 bucco-dentaire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/blog\\\/la-fluorose-dentaire.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/blog\\\/la-fluorose-dentaire.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/fluorose.jpg\",\"datePublished\":\"2021-07-05T18:13:00+00:00\",\"dateModified\":\"2021-07-06T04:05:45+00:00\",\"description\":\"La fluorose dentaire est une l\u00e9g\u00e8re modification de l'aspect des dents, g\u00e9n\u00e9ralement sous la forme de tr\u00e8s l\u00e9g\u00e8res marques blanches ou jaun\u00e2tres.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/blog\\\/la-fluorose-dentaire.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/blog\\\/la-fluorose-dentaire.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/blog\\\/la-fluorose-dentaire.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/fluorose.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/fluorose.jpg\",\"width\":640,\"height\":356,\"caption\":\"La fluorose dentaire\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/blog\\\/la-fluorose-dentaire.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La fluorose dentaire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/#website\",\"url\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/\",\"name\":\"Ma sant\u00e9 bucco-dentaire\",\"description\":\"Informations et conseils dentaires pour patient\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/#\\\/schema\\\/person\\\/b60c4ef676e6f6aecf24be3a2b1d7f42\"},\"alternateName\":\"Sant\u00e9 bucco-dentaire\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/#\\\/schema\\\/person\\\/b60c4ef676e6f6aecf24be3a2b1d7f42\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Ma-sante-dentaire2.jpg\",\"url\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Ma-sante-dentaire2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Ma-sante-dentaire2.jpg\",\"width\":290,\"height\":75,\"caption\":\"Admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Ma-sante-dentaire2.jpg\"},\"sameAs\":[\"https:\\\/\\\/www.lecourrierdudentiste.com\\\/lepatient\",\"https:\\\/\\\/www.facebook.com\\\/Ma-sant-bucco-dentaire-106538034609903\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La fluorose dentaire - Fluorure - Ma sant\u00e9 bucco-dentaire","description":"La fluorose dentaire est une l\u00e9g\u00e8re modification de l'aspect des dents, g\u00e9n\u00e9ralement sous la forme de tr\u00e8s l\u00e9g\u00e8res marques blanches ou jaun\u00e2tres.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html","og_locale":"fr_FR","og_type":"article","og_title":"La fluorose dentaire - Fluorure - Ma sant\u00e9 bucco-dentaire","og_description":"La fluorose dentaire est une l\u00e9g\u00e8re modification de l'aspect des dents, g\u00e9n\u00e9ralement sous la forme de tr\u00e8s l\u00e9g\u00e8res marques blanches ou jaun\u00e2tres.","og_url":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html","og_site_name":"Ma sant\u00e9 bucco-dentaire","article_publisher":"https:\/\/www.facebook.com\/Ma-sant-bucco-dentaire-106538034609903","article_author":"https:\/\/www.facebook.com\/Ma-sant-bucco-dentaire-106538034609903","article_published_time":"2021-07-05T18:13:00+00:00","article_modified_time":"2021-07-06T04:05:45+00:00","og_image":[{"width":640,"height":356,"url":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2021\/07\/fluorose.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html#article","isPartOf":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html"},"author":{"name":"Admin","@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/#\/schema\/person\/b60c4ef676e6f6aecf24be3a2b1d7f42"},"headline":"La fluorose dentaire","datePublished":"2021-07-05T18:13:00+00:00","dateModified":"2021-07-06T04:05:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html"},"wordCount":516,"publisher":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/#\/schema\/person\/b60c4ef676e6f6aecf24be3a2b1d7f42"},"image":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2021\/07\/fluorose.jpg","keywords":["Fluor","Fluorose dentaire","Fluorure"],"articleSection":["BLOG"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html","url":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html","name":"La fluorose dentaire - Fluorure - Ma sant\u00e9 bucco-dentaire","isPartOf":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html#primaryimage"},"image":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2021\/07\/fluorose.jpg","datePublished":"2021-07-05T18:13:00+00:00","dateModified":"2021-07-06T04:05:45+00:00","description":"La fluorose dentaire est une l\u00e9g\u00e8re modification de l'aspect des dents, g\u00e9n\u00e9ralement sous la forme de tr\u00e8s l\u00e9g\u00e8res marques blanches ou jaun\u00e2tres.","breadcrumb":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html#primaryimage","url":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2021\/07\/fluorose.jpg","contentUrl":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2021\/07\/fluorose.jpg","width":640,"height":356,"caption":"La fluorose dentaire"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/blog\/la-fluorose-dentaire.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lecourrierdudentiste.com\/lepatient"},{"@type":"ListItem","position":2,"name":"La fluorose dentaire"}]},{"@type":"WebSite","@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/#website","url":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/","name":"Ma sant\u00e9 bucco-dentaire","description":"Informations et conseils dentaires pour patient","publisher":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/#\/schema\/person\/b60c4ef676e6f6aecf24be3a2b1d7f42"},"alternateName":"Sant\u00e9 bucco-dentaire","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/#\/schema\/person\/b60c4ef676e6f6aecf24be3a2b1d7f42","name":"Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2020\/11\/Ma-sante-dentaire2.jpg","url":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2020\/11\/Ma-sante-dentaire2.jpg","contentUrl":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2020\/11\/Ma-sante-dentaire2.jpg","width":290,"height":75,"caption":"Admin"},"logo":{"@id":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2020\/11\/Ma-sante-dentaire2.jpg"},"sameAs":["https:\/\/www.lecourrierdudentiste.com\/lepatient","https:\/\/www.facebook.com\/Ma-sant-bucco-dentaire-106538034609903"]}]}},"modified_by":"Admin","jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-content\/uploads\/2021\/07\/fluorose.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/posts\/1630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/comments?post=1630"}],"version-history":[{"count":5,"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/posts\/1630\/revisions"}],"predecessor-version":[{"id":1639,"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/posts\/1630\/revisions\/1639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/media\/1631"}],"wp:attachment":[{"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/media?parent=1630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/categories?post=1630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lecourrierdudentiste.com\/lepatient\/wp-json\/wp\/v2\/tags?post=1630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}